{"id":5005,"date":"2023-04-29T13:11:48","date_gmt":"2023-04-29T10:11:48","guid":{"rendered":"https:\/\/stage.www.cobalt.legal\/expert\/renata-cibulskiene\/"},"modified":"2026-01-23T11:42:17","modified_gmt":"2026-01-23T09:42:17","slug":"renata-cibulskiene","status":"publish","type":"expert","link":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/","title":{"rendered":"Renata Cibulskien\u0117"},"featured_media":40307,"template":"","country":[92],"group":[112],"lawyer_position":[346],"position":[320],"class_list":["post-5005","expert","type-expert","status-publish","has-post-thumbnail","hentry","country-lithuania-lt","group-lawyers-lt","lawyer_position-vyresnieji-teisininkai","position-patareja"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Renata Cibulskien\u0117 | COBALT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/\" \/>\n<meta property=\"og:locale\" content=\"lt_LT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Renata Cibulskien\u0117\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/\" \/>\n<meta property=\"og:site_name\" content=\"COBALT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CobaltLegal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T09:42:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/renata-cibulskiene-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2797\" \/>\n\t<meta property=\"og:image:height\" content=\"2447\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\u0117\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/renata-cibulskiene\\\/\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/renata-cibulskiene\\\/\",\"name\":\"Renata Cibulskien\u0117 | COBALT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/renata-cibulskiene\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/renata-cibulskiene\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/renata-cibulskiene-1.jpg\",\"datePublished\":\"2023-04-29T10:11:48+00:00\",\"dateModified\":\"2026-01-23T09:42:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/renata-cibulskiene\\\/#breadcrumb\"},\"inLanguage\":\"lt-LT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/renata-cibulskiene\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/renata-cibulskiene\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/renata-cibulskiene-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/renata-cibulskiene-1.jpg\",\"width\":2797,\"height\":2447},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/renata-cibulskiene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Renata Cibulskien\u0117\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#website\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/\",\"name\":\"COBALT\",\"description\":\"Top-tier law services in Estonia, Latvia and Lithuania\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"lt-LT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#organization\",\"name\":\"COBALT\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cobalt-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cobalt-logo.png\",\"width\":400,\"height\":116,\"caption\":\"COBALT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CobaltLegal\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cobalt-legal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Renata Cibulskien\u0117 | COBALT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/","og_locale":"lt_LT","og_type":"article","og_title":"Renata Cibulskien\u0117","og_url":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/","og_site_name":"COBALT","article_publisher":"https:\/\/www.facebook.com\/CobaltLegal\/","article_modified_time":"2026-01-23T09:42:17+00:00","og_image":[{"width":2797,"height":2447,"url":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/renata-cibulskiene-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minut\u0117"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/","url":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/","name":"Renata Cibulskien\u0117 | COBALT","isPartOf":{"@id":"https:\/\/www.cobalt.legal\/lt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/#primaryimage"},"image":{"@id":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/renata-cibulskiene-1.jpg","datePublished":"2023-04-29T10:11:48+00:00","dateModified":"2026-01-23T09:42:17+00:00","breadcrumb":{"@id":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/#breadcrumb"},"inLanguage":"lt-LT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/"]}]},{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/#primaryimage","url":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/renata-cibulskiene-1.jpg","contentUrl":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/renata-cibulskiene-1.jpg","width":2797,"height":2447},{"@type":"BreadcrumbList","@id":"https:\/\/www.cobalt.legal\/lt\/people\/renata-cibulskiene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cobalt.legal\/lt\/"},{"@type":"ListItem","position":2,"name":"Renata Cibulskien\u0117"}]},{"@type":"WebSite","@id":"https:\/\/www.cobalt.legal\/lt\/#website","url":"https:\/\/www.cobalt.legal\/lt\/","name":"COBALT","description":"Top-tier law services in Estonia, Latvia and Lithuania","publisher":{"@id":"https:\/\/www.cobalt.legal\/lt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cobalt.legal\/lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"lt-LT"},{"@type":"Organization","@id":"https:\/\/www.cobalt.legal\/lt\/#organization","name":"COBALT","url":"https:\/\/www.cobalt.legal\/lt\/","logo":{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/www.cobalt.legal\/lt\/#\/schema\/logo\/image\/","url":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/cobalt-logo.png","contentUrl":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/cobalt-logo.png","width":400,"height":116,"caption":"COBALT"},"image":{"@id":"https:\/\/www.cobalt.legal\/lt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CobaltLegal\/","https:\/\/www.linkedin.com\/company\/cobalt-legal"]}]}},"_links":{"self":[{"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/expert\/5005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/expert"}],"about":[{"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/types\/expert"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/media\/40307"}],"wp:attachment":[{"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/media?parent=5005"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/country?post=5005"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/group?post=5005"},{"taxonomy":"lawyer_position","embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/lawyer_position?post=5005"},{"taxonomy":"position","embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/position?post=5005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}