{"id":7049,"date":"2023-04-14T12:11:44","date_gmt":"2023-04-14T09:11:44","guid":{"rendered":"https:\/\/stage.www.cobalt.legal\/expert\/lauris-liepa-2\/"},"modified":"2026-05-18T21:29:58","modified_gmt":"2026-05-18T18:29:58","slug":"lauris-liepa-2","status":"publish","type":"expert","link":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/","title":{"rendered":"Lauris Liepa"},"featured_media":38364,"template":"","country":[97],"group":[93],"lawyer_position":[346],"position":[102],"class_list":["post-7049","expert","type-expert","status-publish","has-post-thumbnail","hentry","country-latvia-lt","group-partners-lt","lawyer_position-vyresnieji-teisininkai","position-managing-partner-lt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.3) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lauris Liepa | COBALT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/\" \/>\n<meta property=\"og:locale\" content=\"lt_LT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lauris Liepa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/\" \/>\n<meta property=\"og:site_name\" content=\"COBALT\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CobaltLegal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-18T18:29:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/lauris-liepa-2044x1788-4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2044\" \/>\n\t<meta property=\"og:image:height\" content=\"1788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minut\u0117\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/lauris-liepa-2\\\/\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/lauris-liepa-2\\\/\",\"name\":\"Lauris Liepa | COBALT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/lauris-liepa-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/lauris-liepa-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/lauris-liepa-2044x1788-4.jpg\",\"datePublished\":\"2023-04-14T09:11:44+00:00\",\"dateModified\":\"2026-05-18T18:29:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/lauris-liepa-2\\\/#breadcrumb\"},\"inLanguage\":\"lt-LT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/lauris-liepa-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/lauris-liepa-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/lauris-liepa-2044x1788-4.jpg\",\"contentUrl\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/lauris-liepa-2044x1788-4.jpg\",\"width\":2044,\"height\":1788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/people\\\/lauris-liepa-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lauris Liepa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#website\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/\",\"name\":\"COBALT\",\"description\":\"Top-tier law services in Estonia, Latvia and Lithuania\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"lt-LT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#organization\",\"name\":\"COBALT\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"lt-LT\",\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cobalt-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.cobalt.legal\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/cobalt-logo.png\",\"width\":400,\"height\":116,\"caption\":\"COBALT\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cobalt.legal\\\/lt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CobaltLegal\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/cobalt-legal\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lauris Liepa | COBALT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/","og_locale":"lt_LT","og_type":"article","og_title":"Lauris Liepa","og_url":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/","og_site_name":"COBALT","article_publisher":"https:\/\/www.facebook.com\/CobaltLegal\/","article_modified_time":"2026-05-18T18:29:58+00:00","og_image":[{"width":2044,"height":1788,"url":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/lauris-liepa-2044x1788-4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minut\u0117"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/","url":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/","name":"Lauris Liepa | COBALT","isPartOf":{"@id":"https:\/\/www.cobalt.legal\/lt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/#primaryimage"},"image":{"@id":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/lauris-liepa-2044x1788-4.jpg","datePublished":"2023-04-14T09:11:44+00:00","dateModified":"2026-05-18T18:29:58+00:00","breadcrumb":{"@id":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/#breadcrumb"},"inLanguage":"lt-LT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/"]}]},{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/#primaryimage","url":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/lauris-liepa-2044x1788-4.jpg","contentUrl":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/lauris-liepa-2044x1788-4.jpg","width":2044,"height":1788},{"@type":"BreadcrumbList","@id":"https:\/\/www.cobalt.legal\/lt\/people\/lauris-liepa-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.cobalt.legal\/lt\/"},{"@type":"ListItem","position":2,"name":"Lauris Liepa"}]},{"@type":"WebSite","@id":"https:\/\/www.cobalt.legal\/lt\/#website","url":"https:\/\/www.cobalt.legal\/lt\/","name":"COBALT","description":"Top-tier law services in Estonia, Latvia and Lithuania","publisher":{"@id":"https:\/\/www.cobalt.legal\/lt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cobalt.legal\/lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"lt-LT"},{"@type":"Organization","@id":"https:\/\/www.cobalt.legal\/lt\/#organization","name":"COBALT","url":"https:\/\/www.cobalt.legal\/lt\/","logo":{"@type":"ImageObject","inLanguage":"lt-LT","@id":"https:\/\/www.cobalt.legal\/lt\/#\/schema\/logo\/image\/","url":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/cobalt-logo.png","contentUrl":"https:\/\/www.cobalt.legal\/wp-content\/uploads\/2023\/04\/cobalt-logo.png","width":400,"height":116,"caption":"COBALT"},"image":{"@id":"https:\/\/www.cobalt.legal\/lt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CobaltLegal\/","https:\/\/www.linkedin.com\/company\/cobalt-legal"]}]}},"_links":{"self":[{"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/expert\/7049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/expert"}],"about":[{"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/types\/expert"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/media\/38364"}],"wp:attachment":[{"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/media?parent=7049"}],"wp:term":[{"taxonomy":"country","embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/country?post=7049"},{"taxonomy":"group","embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/group?post=7049"},{"taxonomy":"lawyer_position","embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/lawyer_position?post=7049"},{"taxonomy":"position","embeddable":true,"href":"https:\/\/www.cobalt.legal\/lt\/wp-json\/wp\/v2\/position?post=7049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}